{"id":149,"date":"2024-12-20T17:20:29","date_gmt":"2024-12-20T16:20:29","guid":{"rendered":"https:\/\/wellness-nutrition-business.com\/index.php\/conditions-generales\/"},"modified":"2024-12-20T17:20:29","modified_gmt":"2024-12-20T16:20:29","slug":"conditions-generales","status":"publish","type":"page","link":"https:\/\/wellness-nutrition-business.com\/it\/conditions-generales\/","title":{"rendered":"Termini e condizioni generali"},"content":{"rendered":"<!-- This legal document was generated by Complianz Terms &amp; Conditions https:\/\/wordpress.org\/plugins\/complianz-terms-conditions -->\n<div id=\"cmplz-document\" class=\"cmplz-document cmplz-terms-conditions\"><p><i>I termini e le condizioni sono stati aggiornati l&rsquo;ultima volta il 20 Dicembre 2024<\/i><\/p><h2>1. Introduzione<\/h2><p>I presenti Termini e condizioni si applicano a questo sito web e alle transazioni relative ai nostri prodotti e servizi. L'utente potrebbe essere soggetto ad altri contratti relativi al suo rapporto con noi o a qualsiasi prodotto o servizio ricevuto da noi. Se una qualsiasi disposizione di questi accordi aggiuntivi \u00e8 in conflitto con una qualsiasi disposizione dei presenti Termini, le disposizioni di questi accordi aggiuntivi avranno la priorit\u00e0 e prevarranno.<\/p><h2>2. Vincolo<\/h2><p>Registrandosi, accedendo o utilizzando in altro modo questo sito web, l'utente accetta di essere vincolato da questi Termini e condizioni di seguito riportati. Il semplice utilizzo di questo sito web implica la conoscenza e l'accettazione di questi Termini e condizioni. In alcuni casi specifici, possiamo anche chiedere all'utente di rispettarli integralmente.<\/p><h2>3. Comunicazione elettronica<\/h2><p>Utilizzando questo sito web o comunicando con noi per via elettronica, lei accetta e riconosce che possiamo comunicare con lei elettronicamente sul nostro sito web o inviandole un'e-mail, e accetta che tutti gli accordi, gli avvisi, le divulgazioni e le altre comunicazioni che le forniamo elettronicamente soddisfino qualsiasi requisito legale, incluso ma non limitato al requisito che tali comunicazioni debbano essere in forma scritta.<\/p><h2>4. Propriet\u00e0 intellettuale<\/h2><p>Noi o i nostri licenziatari possediamo e controlliamo tutti i diritti d'autore e gli altri diritti di propriet\u00e0 intellettuale del sito web e dei dati, delle informazioni e delle altre risorse visualizzate o accessibili all'interno del sito web.<\/p><p class=\"cmplz-subtitle\">4.1 Tutti i diritti riservati<\/p><p>A meno che il contenuto specifico non imponga diversamente, all'utente non viene concessa una licenza o qualsiasi altro diritto in base a diritti d'autore, marchi, brevetti o altri diritti di propriet\u00e0 intellettuale. Ci\u00f2 significa che non potrete utilizzare, copiare, riprodurre, eseguire, mostrare, distribuire, incorporare in qualsiasi mezzo elettronico, alterare, decompilare, trasferire, scaricare, trasmettere, monetizzare, vendere o commercializzare qualsiasi risorsa di questo sito web in qualsiasi forma, senza il nostro previo permesso scritto, tranne e solo nella misura in cui sia diversamente stabilito in regolamenti di legge obbligatori (come il diritto di citazione).<\/p><h2>5. Newsletter<\/h2><p>Nonostante quanto sopra, \u00e8 possibile inoltrare la nostra newsletter in forma elettronica ad altre persone che potrebbero essere interessate a visitare il nostro sito web.<\/p><h2>6. Propriet\u00e0 di terzi<\/h2><p>Il nostro sito web pu\u00f2 contenere link o altri riferimenti a siti web di altre parti. Non controlliamo n\u00e9 approviamo il contenuto dei siti web di altre parti che sono collegati a questo sito. I prodotti e i servizi offerti da altri siti web sono soggetti ai termini e alle condizioni applicabili di queste tre parti. Le opinioni espresse o il materiale che appare su questi siti web non sono necessariamente sostenute o approvate da noi.<\/p><p>Non sono responsabile delle pratiche sulla privacy o del contenuto di questi siti web. Lei sopporta tutti i rischi associati all'uso di questi siti web e di qualsiasi servizio di terzi collegato. Non accetteremo alcuna responsabilit\u00e0 per eventuali perdite o danni in qualsiasi modo, comunque causati, derivanti dalla vostra divulgazione a terzi di informazioni personali.<\/p><h2>7. Utilizzo responsabile<\/h2><p>Visitando il nostro sito web, l'utente accetta di utilizzarlo solo per gli scopi previsti e come consentito da queste Condizioni, da qualsiasi contratto aggiuntivo con noi, e dalle leggi e dai regolamenti applicabili, nonch\u00e9 dalle pratiche online generalmente accettate e dalle linee guida del settore. Non \u00e8 consentito utilizzare il nostro sito web o i nostri servizi per utilizzare, pubblicare o distribuire materiale che consiste in (o \u00e8 collegato a) software per un computer spento; utilizzare i dati raccolti dal nostro sito web per qualsiasi attivit\u00e0 di marketing diretto; o impegnarsi in qualsiasi attivit\u00e0 di raccolta dati sistematica o automatizzata su o in relazione al nostro sito web.<\/p><p>\u00c8 severamente vietato intraprendere qualsiasi attivit\u00e0 che causi, o possa causare, danni al sito web o che interferisca con le prestazioni, la disponibilit\u00e0 o l'accessibilit\u00e0 del sito web.<\/p><p>Possiamo trattenere il rimborso fino a quando non abbiamo ricevuto la merce indietro o lei ha fornito la prova di aver rispedito la merce, qualunque sia la prima ipotesi.<\/p><h2>8. Contenuto pubblicato da te<\/h2><p>Possiamo fornire vari strumenti di comunicazione aperta sul nostro sito web, come commenti al blog, post sul blog, forum, blog, valutazioni e recensioni e vari servizi di social media. Potrebbe non essere possibile per noi controllare o monitorare tutti i contenuti che voi o altri possono condividere o inviare su o attraverso il nostro sito web. Tuttavia, ci riserviamo il diritto di rivedere il contenuto e di monitorare tutti gli usi e le attivit\u00e0 sul nostro sito web, e di rimuovere o rifiutare qualsiasi contenuto a nostra esclusiva discrezione. Pubblicando informazioni o utilizzando in altro modo uno qualsiasi degli strumenti di comunicazione aperti menzionati, l'utente accetta che il suo contenuto sia conforme ai presenti Termini e condizioni e non sia illegale o illecito o violi i diritti legali di qualsiasi persona.<\/p><h2>9. Presentazione di idee<\/h2><p>Non presentare idee, invenzioni, opere d'autore o altre informazioni che possono essere considerate propriet\u00e0 intellettuale propria che vorresti presentarci, a meno che non abbiamo prima firmato un accordo sulla propriet\u00e0 intellettuale o un accordo di non divulgazione. Se ce lo riveli in assenza di tale accordo scritto, ci concedi una licenza mondiale, irrevocabile, non esclusiva, priva di royalty per utilizzare, riprodurre, memorizzare, adattare, pubblicare, tradurre e distribuire il tuo contenuto in qualsiasi media esistente o futuro.<\/p><h2>10. Cessazione dell'uso<\/h2><p>Lei pu\u00f2, a sua esclusiva discrezione, in qualsiasi momento modificare o interrompere l'accesso, temporaneamente o permanentemente, al sito web o a uno qualsiasi dei servizi offerti su di esso. Lei accetta che non saremo responsabili nei Suoi confronti o nei confronti di terzi per qualsiasi modifica, sospensione o interruzione del Suo accesso o uso del sito web o di qualsiasi contenuto che Lei possa aver condiviso sul sito web. Non avr\u00e0 diritto ad alcun indennizzo o altro pagamento, anche se alcune caratteristiche, impostazioni, e\/o qualsiasi Contenuto che lei ha contribuito o su cui ha fatto affidamento, sono permanentemente persi. L'utente non pu\u00f2 eludere o aggirare, o tentare di eludere o aggirare, qualsiasi misura di restrizione dell'accesso al nostro sito web.<\/p><h2>11. Garanzie e responsabilit\u00e0<\/h2><p>Niente in questa sezione limiter\u00e0 o escluder\u00e0 qualsiasi garanzia implicita per legge che sarebbe illegale limitare o escludere. Questo sito web e tutti i contenuti del sito web sono forniti su una base \"cos\u00ec com'\u00e8\" e \"come disponibile\" e possono includere imprecisioni o errori tipografici. Decliniamo espressamente ogni garanzia di qualsiasi tipo, espressa o implicita, in merito alla disponibilit\u00e0, all'accuratezza o alla completezza dei Contenuti. Non garantiamo che:<\/p><p><ul>\n                    <li>questo sito web o i nostri contenuti soddisfano le vostre esigenze;<\/li>\n                    <li>questo sito web sar\u00e0 disponibile in modo ininterrotto, tempestivo, sicuro o senza errori<\/li>\n        <\/ul><\/p><p>Nulla di quanto contenuto in questo sito web costituisce o intende costituire consulenza legale, finanziaria o medica di alcun tipo. In caso di necessit\u00e0, si prega di consultare un professionista appropriato.<\/p><p>Le seguenti disposizioni di questa sezione si applicheranno nella misura massima consentita dalla legge applicabile e non limiteranno o escluderanno la nostra responsabilit\u00e0 in relazione a qualsiasi questione che sarebbe illegale o illegittima per noi limitare o escludere la nostra responsabilit\u00e0. In nessun caso saremo responsabili di eventuali danni diretti o indiretti (compresi i danni per perdita di profitto o di utilizzo, perdita o distruzione di dati, software o database, o perdita o danneggiamento di propriet\u00e0 o dati) derivanti dall'accesso o dall'utilizzo del nostro sito web.<\/p><p>Tranne nella misura in cui qualsiasi contratto aggiuntivo dichiara espressamente il contrario, la nostra massima responsabilit\u00e0 nei vostri confronti per tutti i danni derivanti da o relativi al sito web o a qualsiasi prodotto e servizio commercializzato o venduto attraverso il sito web, indipendentemente dalla forma di azione legale che impone la responsabilit\u00e0 (sia nel contratto, equit\u00e0, negligenza, condotta intenzionale, torto o altro) sar\u00e0 limitata al prezzo totale che avete pagato a noi per acquistare tali prodotti o servizi o utilizzare il sito web. Tale limite si applicher\u00e0 integralmente a tutti i vostri reclami, azioni e cause di azione di qualsiasi tipo e natura.<\/p><h2>12. La privacy<\/h2><p>Per accedere al nostro sito web e\/o ai nostri servizi, potrebbe essere richiesto all'utente di fornire alcune informazioni su di s\u00e9 nell'ambito del processo di registrazione. L'utente accetta che qualsiasi informazione fornita sia sempre accurata, corretta e aggiornata.<\/p><p>Abbiamo sviluppato una politica per affrontare qualsiasi preoccupazione sulla privacy che potresti avere.&nbsp;For more information, please see our <a href=\"\">Dichiarazione sulla privacy<\/a> and our <a href=\"\">Informativa sui cookie<\/a>.<\/p><h2>13. L'accessibilit\u00e0<\/h2><p>Ci impegniamo a rendere il contenuto che forniamo accessibile agli individui con disabilit\u00e0. Se hai una disabilit\u00e0 e non sei in grado di accedere a qualsiasi parte del nostro sito web a causa della tua disabilit\u00e0, ti chiediamo di darci una notifica includendo una descrizione dettagliata del problema che hai incontrato. Se il problema \u00e8 facilmente identificabile e risolvibile in conformit\u00e0 con gli strumenti e le tecniche informatiche standard del settore, lo risolveremo prontamente.<\/p><h2>14. Restrizioni all'esportazione \/ Conformit\u00e0 legale<\/h2><p>\u00c8 vietato l'accesso al sito web da territori o paesi in cui il Contenuto o l'acquisto di prodotti o servizi venduti sul sito web sono illegali. Non \u00e8 consentito utilizzare questo sito web in violazione delle leggi e dei regolamenti che disciplinano lo sport in Francia.<\/p><h2>15. Marketing di affiliazione<\/h2><p>Attraverso questo sito web \u00e8 possibile intraprendere un'attivit\u00e0 di marketing affiliato in cui riceviamo una percentuale o una commissione sulla vendita di servizi o prodotti su o attraverso questo sito web. Possiamo anche ricevere sponsorizzazioni o altre forme di compenso pubblicitario da aziende. Questa informativa ha lo scopo di rispettare i requisiti legali in materia di marketing e pubblicit\u00e0 eventualmente applicabili, come ad esempio le norme della Federal Trade Commission degli Stati Uniti.<\/p><h2>16. Assegnazione<\/h2><p>Non pu\u00f2 assegnare, trasferire o subappaltare nessuno dei Suoi diritti e\/o obblighi ai sensi di questi Termini e condizioni, in tutto o in parte, a terzi senza il nostro previo consenso scritto. Qualsiasi accordo raggiunto in violazione della presente Sezione sar\u00e0 nullo.<\/p><h2>17. Violazione dei presenti termini e condizioni<\/h2><p>Senza pregiudicare gli altri nostri diritti ai sensi di questi Termini e Condizioni, se l'utente viola questi Termini e Condizioni in qualsiasi modo, possiamo intraprendere le azioni che riteniamo appropriate per affrontare la violazione, compresa la sospensione temporanea o permanente del suo accesso al sito web, contattando il suo provider di servizi Internet per richiedere che blocchi il suo accesso al sito web, e\/o avviare un'azione legale contro l'utente.<\/p><h2>18. Indennizzo<\/h2><p>Lei accetta di indennizzare, difendere e manlevare noi, da e contro qualsiasi reclamo, responsabilit\u00e0, danni, perdite e spese, relative alla sua violazione di questi termini e condizioni, e le leggi applicabili, compresi i diritti di propriet\u00e0 intellettuale e diritti di privacy. Ci rimborser\u00e0 prontamente per i nostri danni, perdite, costi e spese relativi a o derivanti da tali reclami.<\/p><h2>19. Rinuncia<\/h2><p>La mancata applicazione di una qualsiasi delle disposizioni stabilite in questi Termini e Condizioni e in qualsiasi Accordo, o il mancato esercizio di qualsiasi opzione di rescissione, non deve essere interpretata come una rinuncia a tali disposizioni e non pregiudica la validit\u00e0 di questi Termini e Condizioni o di qualsiasi Accordo o parte di esso, o il diritto successivo di applicare ogni singola disposizione.<\/p><h2>20. Lingua<\/h2><p>Questi Termini e Condizioni saranno interpretati e intesi esclusivamente in Francese.&nbsp;Tutti gli avvisi e la corrispondenza saranno scritti esclusivamente in quella lingua.<\/p><h2>21. Accordo integrale<\/h2><p>These Terms and Conditions, together with our <a href=\"\">dichiarazione sulla privacy<\/a> and <a href=\"\">politica dei cookie<\/a>, constitute the entire agreement between you and Wellness Nutrition &amp; Business in relation to your use of this website.<\/p><h2>22. Aggiornamento di questi termini e condizioni<\/h2><p>I presenti Termini e Condizioni possono essere modificati di volta in volta. \u00c8 vostro obbligo controllare periodicamente questi Termini e Condizioni per eventuali modifiche o aggiornamenti. Il dato indicato all'inizio di questi Termini e Condizioni \u00e8 l'ultimo dato di revisione. Le modifiche a questi Termini e Condizioni saranno efficaci dal momento in cui tali modifiche saranno pubblicate su questo sito web. L'uso continuato di questo sito web dopo la pubblicazione di eventuali modifiche o emendamenti sar\u00e0 considerato una notifica del vostro consenso a rispettare ed essere vincolati da questi Termini e Condizioni.<\/p><h2>23. Scelta della legge e della giurisdizione<\/h2><p>I presenti Termini e Condizioni sono regolati dalle leggi della Francia. Qualsiasi controversia relativa ai presenti Termini e Condizioni sar\u00e0 soggetta alla giurisdizione dei tribunali di Francia. Se una qualsiasi parte o disposizione di questi Termini e Condizioni \u00e8 ritenuta da un tribunale o da un'altra autorit\u00e0 non valida e\/o inapplicabile ai sensi della legge applicabile, tale parte o disposizione sar\u00e0 modificata, eliminata e\/o applicata nella misura massima consentita in modo da dare effetto all'intento di questi Termini e Condizioni. Altre disposizioni non saranno interessate.<\/p><h2>24. Informazioni di contatto<\/h2><p>Questo sito web \u00e8 di propriet\u00e0 e gestito da Wellness Nutrition &amp; Business.<\/p><p>Puoi contattarci in merito a questi Termini e Condizioni scrivendoci o inviandoci un&rsquo;e-mail al seguente indirizzo: info&#064;w&#101;&#108;&#108;n&#101;s&#115;-&#110;utr&#105;&#116;i&#111;n&#045;&#098;&#117;&#115;&#105;&#110;&#101;ss&#046;&#099;om<br>ACE MEDIAS<br \/>\r\n3 rue de Thionville<br \/>\r\n57920 K\u00e9dange sur Canner<\/p><h2>25. Scarica<\/h2><p>You can also <a href=\"https:\/\/wellness-nutrition-business.com\/wp-content\/plugins\/complianz-terms-conditions\/download.php\">download<\/a> our Terms and Conditions as a PDF.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mbp_gutenberg_autopost":false,"two_page_speed":[],"footnotes":""},"class_list":["post-149","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/pages\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/pages\/149\/revisions"}],"wp:attachment":[{"href":"https:\/\/wellness-nutrition-business.com\/it\/wp-json\/wp\/v2\/media?parent=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}